{"id":51,"date":"2021-02-21T16:46:48","date_gmt":"2021-02-21T15:46:48","guid":{"rendered":"http:\/\/localhost\/_ahlers\/?page_id=51"},"modified":"2021-03-03T22:38:46","modified_gmt":"2021-03-03T21:38:46","slug":"impressum","status":"publish","type":"page","link":"https:\/\/oldtimerservice-ahlers.de\/index.php\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"<h3>Angaben gem\u00e4\u00df \u00a7 5 TMG<\/h3>\n<p>Roland Ahlers (Einzelunternehmer)<br \/>\nOsttor 17<br \/>\n48324 Sendenhorst<\/p>\n<h3>Kontakt<\/h3>\n<p>Telefon: &#43;&#x34;&#57;&#x20;(&#x30;)&#32;&#x32;&#53;&#x20;&#50;&#x36; &#x32;0&#32;&#x35;&#53;<br \/>\nTelefax: +4&#57;&#32;&#40;&#x30;&#x29;&#x20;&#x32;5 &#50;&#54;&#32;&#x32;&#x30;&#x20;&#x35;5<br \/>\nE-Mail: <a href=\"&#109;&#x61;i&#x6c;&#x74;&#111;&#x3a;i&#x6e;&#x66;&#111;&#x40;o&#x6c;&#x64;&#116;&#x69;m&#x65;&#x72;&#115;&#x65;r&#x76;&#x69;&#99;&#x65;-&#x61;&#x68;&#108;&#x65;r&#x73;&#x2e;&#100;&#x65;\">&#x69;n&#x66;o&#x40;&#111;&#x6c;&#100;t&#x69;m&#x65;&#114;&#x73;&#101;&#x72;&#118;i&#x63;e&#x2d;&#97;&#x68;&#108;&#x65;&#x72;s&#x2e;d&#x65;<\/a><\/p>\n<h3>Haftung f\u00fcr Inhalte<\/h3>\n<p>Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen.<\/p>\n<p>Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.<\/p>\n<h3>Haftung f\u00fcr Links<\/h3>\n<p>Unser Angebot enth\u00e4lt Links zu externen Websites Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar.<\/p>\n<p>Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<\/p>\n<h3>Urheberrecht<\/h3>\n<p>Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind nur f\u00fcr den privaten, nicht kommerziellen Gebrauch gestattet.<\/p>\n<p>Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen.<\/p>\n<h3>Verbraucher\u00adstreit\u00adbeilegung\/Universal\u00adschlichtungs\u00adstelle<\/h3>\n<p>Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen.<\/p>\n<p>Quelle: <a href=\"https:\/\/www.e-recht24.de\/impressum-generator.html\">https:\/\/www.e-recht24.de\/impressum-generator.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angaben gem\u00e4\u00df \u00a7 5 TMG Roland Ahlers (Einzelunternehmer) Osttor 17 48324 Sendenhorst Kontakt Telefon: Telefax: E-Mail: Haftung f\u00fcr Inhalte Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-51","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/oldtimerservice-ahlers.de\/index.php\/wp-json\/wp\/v2\/pages\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldtimerservice-ahlers.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oldtimerservice-ahlers.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oldtimerservice-ahlers.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldtimerservice-ahlers.de\/index.php\/wp-json\/wp\/v2\/comments?post=51"}],"version-history":[{"count":9,"href":"https:\/\/oldtimerservice-ahlers.de\/index.php\/wp-json\/wp\/v2\/pages\/51\/revisions"}],"predecessor-version":[{"id":192,"href":"https:\/\/oldtimerservice-ahlers.de\/index.php\/wp-json\/wp\/v2\/pages\/51\/revisions\/192"}],"wp:attachment":[{"href":"https:\/\/oldtimerservice-ahlers.de\/index.php\/wp-json\/wp\/v2\/media?parent=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}